{"id":497,"date":"2012-11-28T13:22:07","date_gmt":"2012-11-28T13:22:07","guid":{"rendered":"https:\/\/blog.hosting.com.ve\/noticias\/?p=497"},"modified":"2023-12-08T14:42:43","modified_gmt":"2023-12-08T19:12:43","slug":"dominios-mx-o-com-mx-de-los-mas-costosos","status":"publish","type":"post","link":"https:\/\/blog.hosting.com.ve\/noticias\/dominios-mx-o-com-mx-de-los-mas-costosos\/","title":{"rendered":"Dominios mx o com.mx, de los m\u00e1s costosos"},"content":{"rendered":"<p><a href=\"https:\/\/blog.hosting.com.ve\/noticias\/wp-content\/uploads\/2012\/11\/dominio-mx-271112.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-498\" title=\"dominio-mx-271112\" src=\"https:\/\/blog.hosting.com.ve\/noticias\/wp-content\/uploads\/2012\/11\/dominio-mx-271112-300x233.jpg\" alt=\"\" width=\"300\" height=\"233\" srcset=\"https:\/\/blog.hosting.com.ve\/noticias\/wp-content\/uploads\/2012\/11\/dominio-mx-271112-300x233.jpg 300w, https:\/\/blog.hosting.com.ve\/noticias\/wp-content\/uploads\/2012\/11\/dominio-mx-271112.jpg 472w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los dominios mexicanos .mx o .com.mx alcanzaron en el tercer trimestre de 2012 un precio medio de tres mil 40 d\u00f3lares en el mercado secundario.<\/p>\n<p>Los dominios mexicanos .mx o .com.mx son los segundos\u00a0m\u00e1s caros del mundo en el mercado secundario, al lograr en el tercer trimestre de 2012 un precio medio de tres mil 40 d\u00f3lares en el mercado secundario, seg\u00fan el informe trimestral de Sedo.<\/p>\n<p>Sedo.com es la mayor plataforma de compra-venta de dominios de\u00a0Internet\u00a0en el mundo y gestiona la venta de cientos de dominios relacionados con M\u00e9xico.<\/p>\n<p>Indic\u00f3 que los dominios espa\u00f1oles .es son los mejor\u00a0cotizados del mundo con tres mil 125 d\u00f3lares de precio medio.<\/p>\n<p>Apunt\u00f3 que tras la segunda posici\u00f3n de los mexicanos quedar\u00edan los famosos puntocom (.com) siendo los terceros en el ranking de dominios de internet m\u00e1s valorados con un precio medio de dos mil 225 d\u00f3lares.<\/p>\n<p>Expuso que en los \u00faltimos 12 meses el mercado\u00a0\u00a0secundario de dominios de Sedo.com ha negociado la compra venta de m\u00e1s de 36 mil dominios en todo el mundo con un mercado superior a los 70 millones de d\u00f3lares.<\/p>\n<p>La plataforma asever\u00f3 que el mercado secundario de dominios de internet se mantiene estable, con una ligera baja en el tercer trimestre de 2012 respecto al anterior en cuanto a n\u00famero y volumen de transacciones, debido al per\u00edodo estival.<\/p>\n<p>En septiembre el mercado registr\u00f3 un repunte, seg\u00fan el informe trimestral de compra-venta de dominios.<\/p>\n<p>El n\u00famero de dominios vendidos alcanz\u00f3 los ocho mil 181 dominios con un volumen de mercado 15.1 millones de d\u00f3lares.<\/p>\n<p>Los dominios .com contin\u00faan siendo los m\u00e1s comprados y vendidos, acaparando el 49 por ciento del mercado, frente al cinco por ciento de los dominios de internet terminados en .net, el cuatro por ciento de los dominios .org o el dos por ciento de los .info.<\/p>\n<p>Por dominios de primer nivel nacionales los alemanes (.de) son los demandados con m\u00e1s del 15 por ciento del mercado, seguido de los brit\u00e1nicos (.co.uk) con un 4.0 por ciento de mercado y luego los espa\u00f1oles con 2.0 por ciento del mercado.<\/p>\n<p>La Manager General de Sedo para Espa\u00f1a y Am\u00e9rica Latina, Ana Paula V\u00e1zquez, dio a conocer que los dominios .com.mx o .mx tienen a\u00fan un volumen de venta menor, se han registrado 72 compra ventas durante el a\u00f1o.<\/p>\n<p>\u00abSin embargo, el volumen de compra-venta de dominios mexicanos crece de forma pausada pero s\u00f3lida\u00bb, agreg\u00f3 V\u00e1zquez, mexicana residente en Alemania.<\/p>\n<p>\u00abEsto se debe, dijo, al aumento de los internautas y el comercio electr\u00f3nico en M\u00e9xico, que eleva el valor de los dominios nacionales, utilizados ahora por inversores y consumidores de nuestro pa\u00eds a la par que el internacional .com\u00bb, anot\u00f3.<\/p>\n<p>Sedo es la mayor plataforma de compraventa de dominios del mundo y se ha convertido en un referente para analizar la evoluci\u00f3n de esta industria.<\/p>\n<p>Sedo tiene su central en Colonia (Alemania) y filiales en Boston (Estados Unidos) y Londres (Reino Unido) , y cuenta en la actualidad con m\u00e1s de 16 millones de dominios puestos a la venta por m\u00e1s de un mill\u00f3n de usuarios en todo el mundo.<\/p>\n<p>Fuente: vanguardia.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los dominios mexicanos .mx o .com.mx alcanzaron en el tercer trimestre de 2012 un precio medio de tres mil 40 d\u00f3lares en el mercado secundario. Los dominios mexicanos .mx o .com.mx son los segundos\u00a0m\u00e1s caros del mundo en el mercado secundario, al lograr en el tercer trimestre de 2012 un precio medio de tres mil [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-497","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":0,"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hosting.com.ve\/noticias\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}